{"id":38,"count":50,"description":"","link":"https:\/\/sexdollwildnight.com\/en\/product-category\/sexdoll\/on-stock-sexdoll\/tpe-sexdoll\/asia-sexdoll\/","name":"ASIA","slug":"asia-sexdoll","taxonomy":"product_cat","parent":55,"meta":[],"menu_order":16,"_links":{"self":[{"href":"https:\/\/sexdollwildnight.com\/en\/wp-json\/wp\/v2\/product_cat\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sexdollwildnight.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/sexdollwildnight.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/sexdollwildnight.com\/en\/wp-json\/wp\/v2\/product_cat\/55"}],"wp:post_type":[{"href":"https:\/\/sexdollwildnight.com\/en\/wp-json\/wp\/v2\/product?product_cat=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}