{"id":198,"count":67,"description":"","link":"https:\/\/sexdollwildnight.com\/es\/categoria-de-productos\/sexdoll\/en-stock-sexdoll\/158-cm\/","name":"MU\u00d1ECA 158CM","slug":"158-cm","taxonomy":"product_cat","parent":27,"meta":[],"menu_order":5,"_links":{"self":[{"href":"https:\/\/sexdollwildnight.com\/es\/wp-json\/wp\/v2\/product_cat\/198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sexdollwildnight.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/sexdollwildnight.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/sexdollwildnight.com\/es\/wp-json\/wp\/v2\/product_cat\/27"}],"wp:post_type":[{"href":"https:\/\/sexdollwildnight.com\/es\/wp-json\/wp\/v2\/product?product_cat=198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}