{"id":7808,"date":"2025-03-28T18:00:43","date_gmt":"2025-03-28T10:00:43","guid":{"rendered":"https:\/\/sexdollwildnight.com\/?post_type=product&#038;p=7808"},"modified":"2026-01-16T01:34:09","modified_gmt":"2026-01-15T17:34:09","slug":"elegant-lace-cheongsam-style-lingerie-dress-with-side-slit-wildnightsexdoll","status":"publish","type":"product","link":"https:\/\/sexdollwildnight.com\/fr\/produit-2\/elegant-lace-cheongsam-style-lingerie-dress-with-side-slit-wildnightsexdoll\/","title":{"rendered":"Robe de lingerie \u00e9l\u00e9gante en dentelle de style Cheongsam avec fente sur le c\u00f4t\u00e9 - WildNightSexDoll"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7809\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_006-1-400x400.jpeg\" alt=\"\" width=\"400\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_006-1-400x400.jpeg 400w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_006-1-800x800.jpeg 800w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_006-1-280x280.jpeg 280w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_006-1-768x768.jpeg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_006-1-1536x1536.jpeg 1536w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_006-1-510x510.jpeg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_006-1-100x100.jpeg 100w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_006-1.JPEG 1920w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7810\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_007-1-400x400.jpeg\" alt=\"\" width=\"400\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_007-1-400x400.jpeg 400w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_007-1-800x800.jpeg 800w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_007-1-280x280.jpeg 280w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_007-1-768x768.jpeg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_007-1-1536x1536.jpeg 1536w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_007-1-510x510.jpeg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_007-1-100x100.jpeg 100w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_007-1.JPEG 1920w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7811\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_010-400x400.jpeg\" alt=\"\" width=\"400\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_010-400x400.jpeg 400w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_010-800x800.jpeg 800w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_010-280x280.jpeg 280w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_010-768x768.jpeg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_010-1536x1536.jpeg 1536w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_010-510x510.jpeg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_010-100x100.jpeg 100w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_010.JPEG 1920w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7812\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_003-1-400x400.jpeg\" alt=\"\" width=\"400\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_003-1-400x400.jpeg 400w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_003-1-800x800.jpeg 800w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_003-1-280x280.jpeg 280w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_003-1-768x768.jpeg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_003-1-1536x1536.jpeg 1536w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_003-1-510x510.jpeg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_003-1-100x100.jpeg 100w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_003-1.JPEG 1920w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7813\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_005-1-400x400.jpeg\" alt=\"\" width=\"400\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_005-1-400x400.jpeg 400w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_005-1-800x800.jpeg 800w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_005-1-280x280.jpeg 280w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_005-1-768x768.jpeg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_005-1-1536x1536.jpeg 1536w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_005-1-510x510.jpeg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_005-1-100x100.jpeg 100w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/03\/\u4e3b\u56fe_005-1.JPEG 1920w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><script src=\"chrome-extension:\/\/fpelahbljekknahkcaegamhcndkfpfnc\/iFrame.js\" type=\"text\/javascript\"><\/script><\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 100px; top: 2031.78px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>All clothes are one size fits all, suitable for all types of dolls<\/p>\n<p><script src=\"chrome-extension:\/\/fpelahbljekknahkcaegamhcndkfpfnc\/iFrame.js\" type=\"text\/javascript\"><\/script><\/p>","protected":false},"featured_media":7809,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false},"product_brand":[],"product_cat":[213],"product_tag":[216],"class_list":["post-7808","product","type-product","status-publish","has-post-thumbnail","product_cat-sexy-lingerie","product_tag-sexy-lingerie","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-after_add_to_cart"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sexdollwildnight.com\/fr\/wp-json\/wp\/v2\/product\/7808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sexdollwildnight.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sexdollwildnight.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sexdollwildnight.com\/fr\/wp-json\/wp\/v2\/comments?post=7808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sexdollwildnight.com\/fr\/wp-json\/wp\/v2\/media\/7809"}],"wp:attachment":[{"href":"https:\/\/sexdollwildnight.com\/fr\/wp-json\/wp\/v2\/media?parent=7808"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sexdollwildnight.com\/fr\/wp-json\/wp\/v2\/product_brand?post=7808"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sexdollwildnight.com\/fr\/wp-json\/wp\/v2\/product_cat?post=7808"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sexdollwildnight.com\/fr\/wp-json\/wp\/v2\/product_tag?post=7808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}