{"id":12536,"date":"2025-09-14T00:03:15","date_gmt":"2025-09-13T16:03:15","guid":{"rendered":"https:\/\/sexdollwildnight.com\/?post_type=product&#038;p=12536"},"modified":"2026-01-09T02:59:07","modified_gmt":"2026-01-08T18:59:07","slug":"id165d-id4s-selena-cosplay-full-silicone-166cm-5-41ft-dcup-wheat-oral-doll-idoll-2","status":"publish","type":"product","link":"https:\/\/sexdollwildnight.com\/jp\/%e8%a3%bd%e5%93%81\/id165d-id4s-selena-cosplay-full-silicone-166cm-5-41ft-dcup-wheat-oral-doll-idoll-2\/","title":{"rendered":"ID165D-ID4S-jassica sexy Full silicone 166CM-5.41Ft Dcup Wheat oral doll-IDOLL"},"content":{"rendered":"&nbsp;\r\n\r\n&nbsp;\r\n<table style=\"border-collapse: collapse; width: 506.27pt;\" border=\"0\" width=\"675\" cellspacing=\"0\" cellpadding=\"0\">\r\n<tbody>\r\n<tr style=\"height: 13.50pt;\">\r\n<td class=\"et2\" style=\"height: 13.5pt; width: 506.25pt; text-align: center;\" colspan=\"5\" width=\"675\" height=\"18\">IDOLL GIFT<\/td>\r\n<\/tr>\r\n<tr style=\"height: 111.00pt;\">\r\n<td style=\"height: 111.00pt;\" height=\"148\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11996\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7693-267x400.jpg\" alt=\"\" width=\"267\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7693-267x400.jpg 267w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7693-533x800.jpg 533w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7693-768x1152.jpg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7693-1024x1536.jpg 1024w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7693-1365x2048.jpg 1365w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7693-8x12.jpg 8w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7693-510x765.jpg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7693-scaled.jpg 1707w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/td>\r\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11995\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7689-267x400.jpg\" alt=\"\" width=\"267\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7689-267x400.jpg 267w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7689-533x800.jpg 533w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7689-768x1152.jpg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7689-1024x1536.jpg 1024w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7689-1365x2048.jpg 1365w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7689-8x12.jpg 8w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7689-510x765.jpg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7689-scaled.jpg 1707w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/td>\r\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11997\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7705-267x400.jpg\" alt=\"\" width=\"267\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7705-267x400.jpg 267w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7705-533x800.jpg 533w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7705-768x1152.jpg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7705-1024x1536.jpg 1024w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7705-1365x2048.jpg 1365w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7705-8x12.jpg 8w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7705-510x765.jpg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7705-scaled.jpg 1707w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/td>\r\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-12005\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7715-267x400.jpg\" alt=\"\" width=\"267\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7715-267x400.jpg 267w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7715-533x800.jpg 533w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7715-768x1152.jpg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7715-1024x1536.jpg 1024w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7715-1365x2048.jpg 1365w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7715-8x12.jpg 8w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7715-510x765.jpg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7715-scaled.jpg 1707w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/td>\r\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11999\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7681-267x400.jpg\" alt=\"\" width=\"267\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7681-267x400.jpg 267w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7681-533x800.jpg 533w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7681-768x1152.jpg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7681-1024x1536.jpg 1024w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7681-1365x2048.jpg 1365w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7681-8x12.jpg 8w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7681-510x765.jpg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7681-scaled.jpg 1707w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/td>\r\n<\/tr>\r\n<tr style=\"height: 18.00pt;\">\r\n<td style=\"height: 18.00pt;\" height=\"24\">comb<\/td>\r\n<td>Silver lock ring<\/td>\r\n<td>Chain Belt<\/td>\r\n<td>\u30bb\u30af\u30b7\u30fc\u30e9\u30f3\u30b8\u30a7\u30ea\u30fc<\/td>\r\n<td>Makeup brushes<\/td>\r\n<\/tr>\r\n<tr style=\"height: 111.00pt;\">\r\n<td style=\"height: 111.00pt;\" height=\"148\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-12000\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7684-267x400.jpg\" alt=\"\" width=\"267\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7684-267x400.jpg 267w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7684-533x800.jpg 533w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7684-768x1152.jpg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7684-1024x1536.jpg 1024w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7684-1365x2048.jpg 1365w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7684-8x12.jpg 8w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7684-510x765.jpg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7684-scaled.jpg 1707w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/td>\r\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-12001\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7688-267x400.jpg\" alt=\"\" width=\"267\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7688-267x400.jpg 267w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7688-533x800.jpg 533w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7688-768x1152.jpg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7688-1024x1536.jpg 1024w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7688-1365x2048.jpg 1365w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7688-8x12.jpg 8w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7688-510x765.jpg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7688-scaled.jpg 1707w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/td>\r\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-12002\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7692-267x400.jpg\" alt=\"\" width=\"267\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7692-267x400.jpg 267w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7692-533x800.jpg 533w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7692-768x1152.jpg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7692-1024x1536.jpg 1024w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7692-1365x2048.jpg 1365w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7692-8x12.jpg 8w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7692-510x765.jpg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7692-scaled.jpg 1707w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/td>\r\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-12003\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7697-600x400.jpg\" alt=\"\" width=\"600\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7697-600x400.jpg 600w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7697-1200x800.jpg 1200w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7697-768x512.jpg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7697-1536x1024.jpg 1536w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7697-2048x1365.jpg 2048w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7697-18x12.jpg 18w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7697-510x340.jpg 510w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/td>\r\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-12004\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7703-267x400.jpg\" alt=\"\" width=\"267\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7703-267x400.jpg 267w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7703-533x800.jpg 533w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7703-768x1152.jpg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7703-1024x1536.jpg 1024w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7703-1365x2048.jpg 1365w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7703-8x12.jpg 8w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7703-510x765.jpg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/05\/1N1A7703-scaled.jpg 1707w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/td>\r\n<\/tr>\r\n<tr style=\"height: 18.00pt;\">\r\n<td style=\"height: 18.00pt;\" height=\"24\">White Gloves<\/td>\r\n<td>Dance shoes<\/td>\r\n<td>Musturbator special rinser<\/td>\r\n<td>Sexy collar<\/td>\r\n<td>Sexy stockings<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\n<table style=\"border-collapse: collapse; width: 393.77pt;\" border=\"0\" width=\"525\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et2\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Body Name\/Parameter<\/td>\n<td class=\"et2\" style=\"width: 134.25pt;\" width=\"179\">ID165 D<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Overall Height (Including Head)<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">165<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Height (Excluding Head)<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">149<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Neck Length<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">9<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Neck Circumference<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">29<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Shoulder Width<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">39<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Upper Bust<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">102<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Under Bust<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">82<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Cup Size<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">D<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Waist Circumference<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">77.5<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Hip Circumference<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">108<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Vaginal Depth<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">17<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Anal Depth<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">14<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Oral Depth<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">12<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Upper Arm Circumference<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">27<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Lower Arm Circumference<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">23<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Upper Arm Length<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">31<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Lower Arm Length<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">43<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Wrist Circumference<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">14.5<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Palm Length<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">17<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Foot Length<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">24<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Ankle Circumference<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">20<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Thigh Length<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">38<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Calf Length<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">49<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Thigh Circumference<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">60<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Calf Circumference<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">43<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Net Weight (Before Weight Reduction)<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">47kg<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">\u6b63\u5473\u91cd\u91cf<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">39kg<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Packaging Weight<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">54<\/td>\n<\/tr>\n<tr style=\"height: 19.50pt;\">\n<td class=\"et3\" style=\"height: 19.50pt; width: 259.50pt;\" width=\"346\" height=\"26\">Packaging Dimensions<\/td>\n<td class=\"et3\" style=\"width: 134.25pt;\" width=\"179\">150*42*31<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table style=\"border-collapse: collapse; width: 623px; height: 332px;\" border=\"0\" width=\"432\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.5pt; width: 324pt; text-align: center;\" colspan=\"6\" width=\"432\" height=\"18\">\u30ae\u30e3\u30e9\u30ea\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\"><a href=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01805-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12541\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01805-267x400.jpg\" alt=\"\" width=\"267\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01805-267x400.jpg 267w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01805-533x800.jpg 533w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01805-768x1152.jpg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01805-1024x1536.jpg 1024w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01805-1365x2048.jpg 1365w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01805-8x12.jpg 8w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01805-510x765.jpg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01805-scaled.jpg 1707w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/a><\/td>\n<td><a href=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01830-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12538\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01830-267x400.jpg\" alt=\"\" width=\"267\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01830-267x400.jpg 267w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01830-533x800.jpg 533w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01830-768x1152.jpg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01830-1024x1536.jpg 1024w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01830-1365x2048.jpg 1365w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01830-8x12.jpg 8w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01830-510x765.jpg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01830-scaled.jpg 1707w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/a><\/td>\n<td><a href=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01804-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12543\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01804-267x400.jpg\" alt=\"\" width=\"267\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01804-267x400.jpg 267w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01804-533x800.jpg 533w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01804-768x1152.jpg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01804-1024x1536.jpg 1024w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01804-1365x2048.jpg 1365w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01804-8x12.jpg 8w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01804-510x765.jpg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01804-scaled.jpg 1707w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/a><\/td>\n<td><a href=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01785-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12552\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01785-267x400.jpg\" alt=\"\" width=\"267\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01785-267x400.jpg 267w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01785-533x800.jpg 533w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01785-768x1152.jpg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01785-1024x1536.jpg 1024w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01785-1365x2048.jpg 1365w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01785-8x12.jpg 8w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01785-510x765.jpg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01785-scaled.jpg 1707w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/a><\/td>\n<td><a href=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01739-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-12563 size-medium\" src=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01739-267x400.jpg\" alt=\"\" width=\"267\" height=\"400\" srcset=\"https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01739-267x400.jpg 267w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01739-533x800.jpg 533w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01739-768x1152.jpg 768w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01739-1024x1536.jpg 1024w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01739-1365x2048.jpg 1365w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01739-8x12.jpg 8w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01739-510x765.jpg 510w, https:\/\/sexdollwildnight.com\/wp-content\/uploads\/2025\/09\/DSC01739-scaled.jpg 1707w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/a><\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"position: relative; padding-top: 56.25%;\"><iframe style=\"border: 0; position: absolute; top: 0; height: 100%; width: 100%;\" src=\"https:\/\/player.mediadelivery.net\/embed\/563820\/7755b232-9b2b-4757-8e83-9ade72c68c52?autoplay=true&amp;loop=false&amp;muted=false&amp;preload=true&amp;responsive=true\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 131px; top: 1367.02px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n<p><script src=\"chrome-extension:\/\/fpelahbljekknahkcaegamhcndkfpfnc\/iFrame.js\" type=\"text\/javascript\"><\/script><\/p>\n<p><script src=\"chrome-extension:\/\/fpelahbljekknahkcaegamhcndkfpfnc\/iFrame.js\" type=\"text\/javascript\"><\/script><\/p>","protected":false},"featured_media":12556,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false},"product_brand":[504],"product_cat":[491,490,214],"product_tag":[510,91,487,509,99,101],"class_list":["post-12536","product","type-product","status-publish","has-post-thumbnail","product_brand-idoll","product_cat-europe","product_cat-full-silicone-sexdoll","product_cat-sexdoll","product_tag-510","product_tag-166cm","product_tag-cosplay","product_tag-idoll","product_tag-large-breast","product_tag-skinny","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-after_add_to_cart"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sexdollwildnight.com\/jp\/wp-json\/wp\/v2\/product\/12536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sexdollwildnight.com\/jp\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sexdollwildnight.com\/jp\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sexdollwildnight.com\/jp\/wp-json\/wp\/v2\/comments?post=12536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sexdollwildnight.com\/jp\/wp-json\/wp\/v2\/media\/12556"}],"wp:attachment":[{"href":"https:\/\/sexdollwildnight.com\/jp\/wp-json\/wp\/v2\/media?parent=12536"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sexdollwildnight.com\/jp\/wp-json\/wp\/v2\/product_brand?post=12536"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sexdollwildnight.com\/jp\/wp-json\/wp\/v2\/product_cat?post=12536"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sexdollwildnight.com\/jp\/wp-json\/wp\/v2\/product_tag?post=12536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}